{"id":3,"count":2,"description":"","link":"https:\/\/templatekit.jegtheme.com\/squaro\/category\/project-management\/","name":"Project Management","slug":"project-management","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/categories\/3"}],"collection":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}