{"id":91,"date":"2023-10-17T09:00:10","date_gmt":"2023-10-17T09:00:10","guid":{"rendered":"https:\/\/templatekit.jegtheme.com\/squaro\/?p=91"},"modified":"2023-10-23T09:54:01","modified_gmt":"2023-10-23T09:54:01","slug":"10-tips-for-successful-project-management-in-construction","status":"publish","type":"post","link":"https:\/\/templatekit.jegtheme.com\/squaro\/2023\/10\/17\/10-tips-for-successful-project-management-in-construction\/","title":{"rendered":"10 Tips for Successful Project Management in Construction"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"91\" class=\"elementor elementor-91\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3313c7bb e-con-full e-flex e-con e-parent\" data-id=\"3313c7bb\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-626bd646 e-con-full e-flex e-con e-child\" data-id=\"626bd646\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-49a056bc e-con-full e-flex e-con e-child\" data-id=\"49a056bc\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-620cca2b elementor-widget elementor-widget-jkit_post_terms\" data-id=\"620cca2b\" data-element_type=\"widget\" data-widget_type=\"jkit_post_terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-terms jeg_module___6a04ff93a0c87\" ><span class=\"post-terms\"><span class=\"term-list \">Project Management<\/span><\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a2a3e7 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-jkit_post_title\" data-id=\"8a2a3e7\" data-element_type=\"widget\" data-widget_type=\"jkit_post_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-title jeg_module__1_6a04ff93a4049\" ><h2 class=\"post-title style-color \">10 Tips for Successful Project Management in Construction<\/h2><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79ba1d11 e-con-full e-flex e-con e-child\" data-id=\"79ba1d11\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-448c4b32 elementor-widget__width-initial elementor-widget elementor-widget-jkit_post_author\" data-id=\"448c4b32\" data-element_type=\"widget\" data-widget_type=\"jkit_post_author.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-author jeg_module__2_6a04ff93a4a9c\" ><p class=\"post-author \"><img alt='' src='https:\/\/secure.gravatar.com\/avatar\/053afef44f743a309ea1d78a8b349f1f?s=256&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/053afef44f743a309ea1d78a8b349f1f?s=512&#038;d=mm&#038;r=g 2x' class='avatar avatar-256 photo' height='256' width='256' \/><\/p><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30a2b29d e-con-full e-flex e-con e-child\" data-id=\"30a2b29d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17363183 elementor-widget__width-initial elementor-widget elementor-widget-jkit_post_author\" data-id=\"17363183\" data-element_type=\"widget\" data-widget_type=\"jkit_post_author.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-author jeg_module__3_6a04ff93a4f39\" ><p class=\"post-author \">Jane Doe<\/p><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-475c9ffb elementor-widget elementor-widget-jkit_post_date\" data-id=\"475c9ffb\" data-element_type=\"widget\" data-widget_type=\"jkit_post_date.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-date jeg_module__4_6a04ff93a57aa\" ><p class=\"post-date \">October 17, 2023<\/p><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24f271f e-con-full e-flex e-con e-child\" data-id=\"24f271f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0cc959 elementor-widget elementor-widget-jkit_post_featured_image\" data-id=\"4e0cc959\" data-element_type=\"widget\" data-widget_type=\"jkit_post_featured_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-featured-image jeg_module__5_6a04ff93a74a0\" ><div class=\"post-featured-image \"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1200\" src=\"https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/female-caucasian-engineers-with-senior-man-discuss-2022-02-10-01-52-30-utc.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/female-caucasian-engineers-with-senior-man-discuss-2022-02-10-01-52-30-utc.jpg 1800w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/female-caucasian-engineers-with-senior-man-discuss-2022-02-10-01-52-30-utc-300x200.jpg 300w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/female-caucasian-engineers-with-senior-man-discuss-2022-02-10-01-52-30-utc-1024x683.jpg 1024w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/female-caucasian-engineers-with-senior-man-discuss-2022-02-10-01-52-30-utc-768x512.jpg 768w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/female-caucasian-engineers-with-senior-man-discuss-2022-02-10-01-52-30-utc-1536x1024.jpg 1536w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/female-caucasian-engineers-with-senior-man-discuss-2022-02-10-01-52-30-utc-800x533.jpg 800w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f07d152 e-flex e-con-boxed e-con e-parent\" data-id=\"4f07d152\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25cb4292 e-flex e-con-boxed e-con e-child\" data-id=\"25cb4292\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5251008c elementor-widget elementor-widget-heading\" data-id=\"5251008c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">What you Need to Know Before Signing Construction Contracts<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d0f106b elementor-widget elementor-widget-text-editor\" data-id=\"1d0f106b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\tMi tincidunt elit, id quisque ligula ac diam, amet. Vel etiam suspendisse morbi eleifend faucibus eget vestibulum felis. Dictum quis montes, sit sit. Tellus aliquam enim urna, etiam. Mauris posuere vulputate arcu amet, vitae nisi, tellus tincidunt. At feugiat sapien varius id.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba89a50 elementor-widget elementor-widget-text-editor\" data-id=\"3ba89a50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEget quis mi enim, leo lacinia pharetra, semper. Eget in volutpat mollis at volutpat lectus velit, sed auctor. Porttitor fames arcu quis fusce augue enim. Quis at habitant diam at. Suscipit tristique risus, at donec. In turpis vel et quam imperdiet. Ipsum molestie aliquet sodales id est ac volutpat. \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-651315eb elementor-widget elementor-widget-image\" data-id=\"651315eb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1198\" src=\"https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/building-under-construction-with-building-armor-an-2022-10-04-00-15-08-utc.jpg\" class=\"attachment-full size-full wp-image-165\" alt=\"\" srcset=\"https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/building-under-construction-with-building-armor-an-2022-10-04-00-15-08-utc.jpg 1800w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/building-under-construction-with-building-armor-an-2022-10-04-00-15-08-utc-300x200.jpg 300w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/building-under-construction-with-building-armor-an-2022-10-04-00-15-08-utc-1024x682.jpg 1024w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/building-under-construction-with-building-armor-an-2022-10-04-00-15-08-utc-768x511.jpg 768w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/building-under-construction-with-building-armor-an-2022-10-04-00-15-08-utc-1536x1022.jpg 1536w, https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/uploads\/sites\/420\/2023\/10\/building-under-construction-with-building-armor-an-2022-10-04-00-15-08-utc-800x532.jpg 800w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a8e172b elementor-widget elementor-widget-text-editor\" data-id=\"4a8e172b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tElit nisi in eleifend sed nisi. Pulvinar at orci, proin imperdiet commodo consectetur convallis risus. Sed condimentum enim dignissim adipiscing faucibus consequat, urna. Viverra purus et erat auctor aliquam. Risus, volutpat vulputate posuere purus sit congue convallis aliquet. Arcu id augue ut feugiat donec porttitor neque. Mauris, neque ultricies eu vestibulum, bibendum quam lorem id. Dolor lacus, eget nunc lectus in tellus, pharetra, porttitor.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27bf70fb elementor-widget elementor-widget-heading\" data-id=\"27bf70fb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Key Components of a Construction Contract<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-133f5839 elementor-widget elementor-widget-text-editor\" data-id=\"133f5839\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEget quis mi enim, leo lacinia pharetra, semper. Eget in volutpat mollis at volutpat lectus velit, sed auctor. Porttitor fames arcu quis fusce augue enim. Quis at habitant diam at. Suscipit tristique risus, at donec. In turpis vel et quam imperdiet. Ipsum molestie aliquet sodales id est ac volutpat. Dictum quis montes, sit sit. Tellus aliquam enim urna, etiam. Mauris posuere vulputate arcu amet, vitae nisi, tellus tincidunt. At feugiat sapien varius id.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4013db93 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4013db93\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/templatekit.jegtheme.com\/squaro\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lectus id duis vitae porttitor enim gravida morbi vitae placerat<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Eu turpis posuere semper feugiat volutpat elit, ultrices suspendisse<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Suspendisse maecenas ac donec scelerisque diam sed est duis purus<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-square-full\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Auctor rutrum lacus malesuada massa ornare et ultrices at diam dui eget<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39841073 elementor-widget elementor-widget-text-editor\" data-id=\"39841073\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tMi tincidunt elit, id quisque ligula ac diam, amet. Vel etiam suspendisse morbi eleifend faucibus eget vestibulum felis. Dictum quis montes, sit sit. Tellus aliquam enim urna, etiam. Mauris posuere vulputate arcu amet, vitae nisi, tellus tincidunt. At feugiat sapien varius id. Dolor enim eu tortor urna sed duis nulla. Aliquam vestibulum, nulla odio nisl vitae. In aliquet pellentesque aenean hac vestibulum turpis mi bibendum diam. Tempor integer aliquam in vitae.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e6eda1 elementor-widget elementor-widget-heading\" data-id=\"40e6eda1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Foundation of a Successful Construction<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78b71211 elementor-widget elementor-widget-text-editor\" data-id=\"78b71211\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tLectus leo massa amet posuere. Malesuada mattis non convallis quisque. Libero sit et imperdiet bibendum quisque dictum vestibulum in non. Pretium ultricies tempor non est diam. Enim ut enim amet amet integer cursus. Sit ac commodo pretium sed etiam turpis suspendisse at. Aliquam tellus lorem sed ac. Montes, sed mattis pellentesque suscipit accumsan. Cursus viverra aenean magna risus elementum faucibus molestie pellentesque. Arcu ultricies sed mauris vestibulum.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56789f9d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"56789f9d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e35bdfd e-con-full e-flex e-con e-child\" data-id=\"e35bdfd\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6eee713d elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"6eee713d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Share This Post <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27007248 jkit-social-shape shape-square elementor-widget elementor-widget-jkit_social_share\" data-id=\"27007248\" data-element_type=\"widget\" data-widget_type=\"jkit_social_share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-social-share jeg_module__6_6a04ff93ace87\" ><ul class=\"social-share-list\"><li class=\"elementor-repeater-item-2d7a8cc\" data-social=\"facebook\">\n\t\t\t\t<a class=\"facebook social-icon\"><i aria-hidden=\"true\" class=\"jki jki-facebook-light\"><\/i><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-22a127a\" data-social=\"whatsapp\">\n\t\t\t\t<a class=\"whatsapp social-icon\"><i aria-hidden=\"true\" class=\"jki jki-whatsapp-1-light\"><\/i><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-a1da1ca\" data-social=\"linkedin\">\n\t\t\t\t<a class=\"linkedin social-icon\"><i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-f08bc6e\" data-social=\"twitter\">\n\t\t\t\t<a class=\"twitter social-icon\"><i aria-hidden=\"true\" class=\"jki jki-twitter-light\"><\/i><\/a>\n\t\t\t<\/li><\/ul><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f900513 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f900513\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24986ece elementor-widget elementor-widget-jkit_post_comment\" data-id=\"24986ece\" data-element_type=\"widget\" data-widget_type=\"jkit_post_comment.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div  class=\"jeg-elementor-kit jkit-post-comment jeg_module__7_6a04ff93af14b\" ><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Project Management 10 Tips for Successful Project Management in Construction Jane Doe October 17, 2023 What you Need to Know Before Signing Construction Contracts Mi tincidunt elit, id quisque ligula ac diam, amet. Vel etiam suspendisse morbi eleifend faucibus eget vestibulum felis. Dictum quis montes, sit sit. Tellus aliquam enim urna, etiam. Mauris posuere vulputate [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":92,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/posts\/91"}],"collection":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":0,"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/posts\/91\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/media\/92"}],"wp:attachment":[{"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/categories?post=91"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/templatekit.jegtheme.com\/squaro\/wp-json\/wp\/v2\/tags?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}