{"id":5,"count":1,"description":"","link":"https:\/\/templatekit.jegtheme.com\/topspin\/category\/academy\/","name":"Academy","slug":"academy","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/templatekit.jegtheme.com\/topspin\/wp-json\/wp\/v2\/categories\/5"}],"collection":[{"href":"https:\/\/templatekit.jegtheme.com\/topspin\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/templatekit.jegtheme.com\/topspin\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/templatekit.jegtheme.com\/topspin\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}