{"id":7,"count":1,"description":"","link":"https:\/\/templatekit.jegtheme.com\/travisa\/category\/transit-visa\/","name":"Transit Visa","slug":"transit-visa","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/templatekit.jegtheme.com\/travisa\/wp-json\/wp\/v2\/categories\/7"}],"collection":[{"href":"https:\/\/templatekit.jegtheme.com\/travisa\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/templatekit.jegtheme.com\/travisa\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/templatekit.jegtheme.com\/travisa\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}