{"id":6,"count":1,"description":"","link":"https:\/\/templatekit.jegtheme.com\/vinera\/category\/promo\/","name":"Promo","slug":"promo","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/templatekit.jegtheme.com\/vinera\/wp-json\/wp\/v2\/categories\/6"}],"collection":[{"href":"https:\/\/templatekit.jegtheme.com\/vinera\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/templatekit.jegtheme.com\/vinera\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/templatekit.jegtheme.com\/vinera\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}